{"id":683187,"date":"2024-05-16T10:34:20","date_gmt":"2024-05-16T08:34:20","guid":{"rendered":"https:\/\/www.lightdesign.shop\/negozio\/uncategorized\/lombardo-clic-post-4000k-grigio-scuro\/"},"modified":"2026-05-07T17:00:22","modified_gmt":"2026-05-07T15:00:22","slug":"lombardo-clic-post-4000k-grigio-scuro","status":"publish","type":"product","link":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/","title":{"rendered":"Lombardo CLIC POST 4000k &#8211; grigio scuro"},"content":{"rendered":"<h2>CLIC POST 4000k &#8211; grigio scuro<\/h2>\n<p>Il Clic Post, prodotto dal marchio Lombardo, \u00e8 una soluzione ideale per l&#8217;illuminazione esterna. Caratterizzato da un corpo e diffusore in policarbonato verniciato, offre una robusta resistenza agli agenti atmosferici. Questo apparecchio \u00e8 progettato con guarnizioni in silicone per mantenere il grado di protezione IP65, garantendo cos\u00ec la sua impermeabilit\u00e0 all&#8217;acqua e alla polvere. La bulloneria in acciaio inossidabile A4 assicura una maggiore durabilit\u00e0 nel tempo. Il Clic Post \u00e8 disponibile in due versioni: una con attacco GU10 (lampadina non inclusa) e un&#8217;altra con motore LED integrato a tensione di rete. La versione AC-Direct \u00e8 dimmerabile a taglio di fase, offrendo un maggiore controllo sull&#8217;intensit\u00e0 luminosa. Una caratteristica importante \u00e8 che non presenta rischi fotobiologici, classificato come RG0, il che lo rende sicuro per l&#8217;uso. \u00c8 disponibile in diverse finiture, tra cui- nero, grigio e corten, per adattarsi al meglio al tuo ambiente esterno.<\/p>\n<p><em>Sorgente Luminosa: LED 5W &#8211; 600 lumen &#8211; 4000 K &#8211; CRI>80 &#8211; AC DIRECT 220\/240 V &#8211; Dimmerabile &#8211; IP65. Dimensioni: H 75 mm \u00d8 92 mm<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Clic Post, prodotto dal marchio Lombardo, \u00e8 una soluzione ideale per l&#8217;illuminazione esterna. Caratterizzato da un corpo e diffusore in policarbonato verniciato, offre una robusta resistenza agli agenti atmosferici. Questo apparecchio \u00e8 progettato con guarnizioni in silicone per mantenere il grado di protezione IP65, garantendo cos\u00ec la sua impermeabilit\u00e0 all&#8217;acqua e alla polvere. La bulloneria in acciaio inossidabile A4 assicura una maggiore durabilit\u00e0 nel tempo. Il Clic Post \u00e8 disponibile in due versioni: una con attacco GU10 (lampadina non inclusa) e un&#8217;altra con motore LED integrato a tensione di rete<\/p>\n","protected":false},"featured_media":682080,"comment_status":"open","ping_status":"open","template":"","meta":{"_exactmetrics_skip_tracking":false,"_joinchat":[]},"product_brand":[],"product_cat":[399],"product_tag":[4209,4173,391,4203],"class_list":["post-683187","product","type-product","status-publish","has-post-thumbnail","product_cat-outdoor-floor-lights","product_tag-a2810011wt","product_tag-hospitality-en","product_tag-modern-en","product_tag-outdoor-en","pa_ambiente-outdoor-en","pa_brand-lombardo-en","pa_colore-grey","pa_materiale-polycarbonate","pa_stile-modern-en","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lombardo CLIC POST 4000k - grigio scuro - LiD Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lombardo CLIC POST 4000k - grigio scuro\" \/>\n<meta property=\"og:description\" content=\"Il Clic Post, prodotto dal marchio Lombardo, \u00e8 una soluzione ideale per l&#039;illuminazione esterna. Caratterizzato da un corpo e diffusore in policarbonato verniciato, offre una robusta resistenza agli agenti atmosferici. Questo apparecchio \u00e8 progettato con guarnizioni in silicone per mantenere il grado di protezione IP65, garantendo cos\u00ec la sua impermeabilit\u00e0 all&#039;acqua e alla polvere. La bulloneria in acciaio inossidabile A4 assicura una maggiore durabilit\u00e0 nel tempo. Il Clic Post \u00e8 disponibile in due versioni: una con attacco GU10 (lampadina non inclusa) e un&#039;altra con motore LED integrato a tensione di rete\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/\" \/>\n<meta property=\"og:site_name\" content=\"LiD Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LID-Design-757324454392843\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T15:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/05\/LL14804DN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;83\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/\",\"name\":\"Lombardo CLIC POST 4000k - grigio scuro - LiD Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/LL14804DN.jpg\",\"datePublished\":\"2024-05-16T08:34:20+00:00\",\"dateModified\":\"2026-05-07T15:00:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/LL14804DN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/LL14804DN.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lombardo CLIC POST 4000k &#8211; grigio scuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\",\"name\":\"LiD - illumina il tuo mondo\",\"description\":\"Light Design Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#organization\"},\"alternateName\":\"lightdesign.shop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#organization\",\"name\":\"LiD Srl\",\"alternateName\":\"LID design\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LID-Design-757324454392843\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lightdesign.shop\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC-wfhs9IlrFGpIWzx24cMhA\"],\"legalName\":\"Lid Srl\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.lightdesign.shop\\\/termini-e-condizioni\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"38.1249528\",\"longitude\":\"13.3539442\"},\"telephone\":[\"0917478460\",\"+393756953950\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+393756953950\",\"email\":\"customerservice@liddesign.it\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@liddesign.it\",\"vatID\":\"IT06602130822\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#local-main-place-address\",\"streetAddress\":\"via xx settembre 9\",\"addressLocality\":\"Palermo\",\"postalCode\":\"90141\",\"addressRegion\":\"PA\",\"addressCountry\":\"IT\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/outdoor-lamps\\\/outdoor-floor-lights\\\/lombardo-clic-post-4000k-grigio-scuro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo.png\",\"width\":1027,\"height\":759,\"caption\":\"LiD Srl\"}]}<\/script>\n<meta property=\"product:brand\" content=\"Lombardo\" \/>\n<meta property=\"product:price:amount\" content=\"83\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LL14804DN\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Palermo\" \/>\n<meta name=\"geo.position\" content=\"38.1249528;13.3539442\" \/>\n<meta name=\"geo.region\" content=\"Italy\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lombardo CLIC POST 4000k - grigio scuro - LiD Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/","og_locale":"en_US","og_type":"article","og_title":"Lombardo CLIC POST 4000k - grigio scuro","og_description":"Il Clic Post, prodotto dal marchio Lombardo, \u00e8 una soluzione ideale per l'illuminazione esterna. Caratterizzato da un corpo e diffusore in policarbonato verniciato, offre una robusta resistenza agli agenti atmosferici. Questo apparecchio \u00e8 progettato con guarnizioni in silicone per mantenere il grado di protezione IP65, garantendo cos\u00ec la sua impermeabilit\u00e0 all'acqua e alla polvere. La bulloneria in acciaio inossidabile A4 assicura una maggiore durabilit\u00e0 nel tempo. Il Clic Post \u00e8 disponibile in due versioni: una con attacco GU10 (lampadina non inclusa) e un'altra con motore LED integrato a tensione di rete","og_url":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/","og_site_name":"LiD Design","article_publisher":"https:\/\/www.facebook.com\/LID-Design-757324454392843\/","article_modified_time":"2026-05-07T15:00:22+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/05\/LL14804DN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;&nbsp;83","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/","url":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/","name":"Lombardo CLIC POST 4000k - grigio scuro - LiD Design","isPartOf":{"@id":"https:\/\/www.lightdesign.shop\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#primaryimage"},"image":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/05\/LL14804DN.jpg","datePublished":"2024-05-16T08:34:20+00:00","dateModified":"2026-05-07T15:00:22+00:00","breadcrumb":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#primaryimage","url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/05\/LL14804DN.jpg","contentUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/05\/LL14804DN.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lightdesign.shop\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.lightdesign.shop\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Lombardo CLIC POST 4000k &#8211; grigio scuro"}]},{"@type":"WebSite","@id":"https:\/\/www.lightdesign.shop\/en\/#website","url":"https:\/\/www.lightdesign.shop\/en\/","name":"LiD - illumina il tuo mondo","description":"Light Design Shop","publisher":{"@id":"https:\/\/www.lightdesign.shop\/en\/#organization"},"alternateName":"lightdesign.shop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lightdesign.shop\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/www.lightdesign.shop\/en\/#organization","name":"LiD Srl","alternateName":"LID design","url":"https:\/\/www.lightdesign.shop\/en\/","logo":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/LID-Design-757324454392843\/","https:\/\/www.instagram.com\/lightdesign.shop\/","https:\/\/www.youtube.com\/channel\/UC-wfhs9IlrFGpIWzx24cMhA"],"legalName":"Lid Srl","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.lightdesign.shop\/termini-e-condizioni\/"},"address":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"38.1249528","longitude":"13.3539442"},"telephone":["0917478460","+393756953950"],"contactPoint":{"@type":"ContactPoint","telephone":"+393756953950","email":"customerservice@liddesign.it"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@liddesign.it","vatID":"IT06602130822"},{"@type":"PostalAddress","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#local-main-place-address","streetAddress":"via xx settembre 9","addressLocality":"Palermo","postalCode":"90141","addressRegion":"PA","addressCountry":"IT"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/outdoor-lamps\/outdoor-floor-lights\/lombardo-clic-post-4000k-grigio-scuro\/#local-main-organization-logo","url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/06\/logo.png","contentUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/06\/logo.png","width":1027,"height":759,"caption":"LiD Srl"}]},"product_brand":"Lombardo","product_price_amount":"83","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LL14804DN","product_condition":"new","geo.placename":"Palermo","geo.position":{"lat":"38.1249528","long":"13.3539442"},"geo.region":"Italy"},"_links":{"self":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product\/683187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/comments?post=683187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/media\/682080"}],"wp:attachment":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/media?parent=683187"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_brand?post=683187"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_cat?post=683187"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_tag?post=683187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}