{"id":1316211,"date":"2024-12-12T10:24:30","date_gmt":"2024-12-12T09:24:30","guid":{"rendered":"https:\/\/www.lightdesign.shop\/negozio\/uncategorized\/foscarini-chapeaux-v-tavolo-grigio\/"},"modified":"2026-05-07T17:38:57","modified_gmt":"2026-05-07T15:38:57","slug":"foscarini-chapeaux-v-tavolo-grigio","status":"publish","type":"product","link":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/","title":{"rendered":"Foscarini CHAPEAUX V tavolo &#8211; grigio"},"content":{"rendered":"<h2>CHAPEAUX V tavolo &#8211; grigio<\/h2>\n<p>Chapeaux V, del marchio Foscarini, design di Rodolfo Dordoni, \u00e8 una lampada da tavolo a luce diretta e diffusa, elegante e minimale. Il cuore del progetto \u00e8 costituito da tre diffusori intercambiabili \u2013 diversi per forma, materiali e finiture \u2013 appoggiati liberamente su un corpo cilindrico in vetro borosilicato aperto alle estremit\u00e0, che ospita anche la fonte luminosa. Questa, racchiusa in un\u2019ampolla in policarbonato opalino, sembra galleggiare all\u2019interno del vetro. Nella versione V, il diffusore \u00e8 realizzato in vetro incamiciato soffiato a bocca con finitura lucida, permettendo alla luce di attraversarlo parzialmente per creare un\u2019illuminazione morbida e accogliente. Un&#8217;astina in alluminio spazzolato sulla sommit\u00e0 funge da touch dimmer a tre livelli, mantenendo la memoria dell&#8217;ultima impostazione quando usata con un interruttore a parete.<\/p>\n<p><em>Light source: LED included 7,5W &#8211; 2700 K &#8211; 900 lumens &#8211; CRI>90 &#8211; IP20. Dimensions: \u00d8 29 cm  H 47 cm<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chapeaux V, del marchio Foscarini, design di Rodolfo Dordoni, \u00e8 una lampada da tavolo a luce diretta e diffusa, elegante e minimale. Il cuore del progetto \u00e8 costituito da tre diffusori intercambiabili \u2013 diversi per forma, materiali e finiture \u2013 appoggiati liberamente su un corpo cilindrico in vetro borosilicato aperto alle estremit\u00e0, che ospita anche la fonte luminosa. Questa, racchiusa in un\u2019ampolla in policarbonato opalino, sembra galleggiare all\u2019interno del vetro.<\/p>\n","protected":false},"featured_media":1314857,"comment_status":"open","ping_status":"open","template":"","meta":{"_exactmetrics_skip_tracking":false,"_joinchat":[]},"product_brand":[],"product_cat":[3369,407],"product_tag":[4209,4115,4109,4110],"class_list":["post-1316211","product","type-product","status-publish","has-post-thumbnail","product_cat-gift-ideas","product_cat-indoor-table-lamps","product_tag-a2810011wt","product_tag-diffused","product_tag-home-en","product_tag-indoor-en","pa_ambiente-living","pa_brand-foscarini-en","pa_colore-grey","pa_designer-rodolfo-dordoni-en","pa_materiale-glass","pa_stile-contemporary","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Foscarini CHAPEAUX V tavolo - grigio - LiD Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foscarini CHAPEAUX V tavolo - grigio\" \/>\n<meta property=\"og:description\" content=\"Chapeaux V, del marchio Foscarini, design di Rodolfo Dordoni, \u00e8 una lampada da tavolo a luce diretta e diffusa, elegante e minimale. Il cuore del progetto \u00e8 costituito da tre diffusori intercambiabili \u2013 diversi per forma, materiali e finiture \u2013 appoggiati liberamente su un corpo cilindrico in vetro borosilicato aperto alle estremit\u00e0, che ospita anche la fonte luminosa. Questa, racchiusa in un\u2019ampolla in policarbonato opalino, sembra galleggiare all\u2019interno del vetro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/\" \/>\n<meta property=\"og:site_name\" content=\"LiD Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LID-Design-757324454392843\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T15:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/12\/FN3140T200_24E00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;966\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/\",\"name\":\"Foscarini CHAPEAUX V tavolo - grigio - LiD Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FN3140T200_24E00.jpg\",\"datePublished\":\"2024-12-12T09:24:30+00:00\",\"dateModified\":\"2026-05-07T15:38:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FN3140T200_24E00.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/FN3140T200_24E00.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Foscarini CHAPEAUX V tavolo &#8211; grigio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\",\"name\":\"LiD - illumina il tuo mondo\",\"description\":\"Light Design Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#organization\"},\"alternateName\":\"lightdesign.shop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/#organization\",\"name\":\"LiD Srl\",\"alternateName\":\"LID design\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LID-Design-757324454392843\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lightdesign.shop\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC-wfhs9IlrFGpIWzx24cMhA\"],\"legalName\":\"Lid Srl\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.lightdesign.shop\\\/termini-e-condizioni\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"38.1249528\",\"longitude\":\"13.3539442\"},\"telephone\":[\"0917478460\",\"+393756953950\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+393756953950\",\"email\":\"customerservice@liddesign.it\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@liddesign.it\",\"vatID\":\"IT06602130822\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#local-main-place-address\",\"streetAddress\":\"via xx settembre 9\",\"addressLocality\":\"Palermo\",\"postalCode\":\"90141\",\"addressRegion\":\"PA\",\"addressCountry\":\"IT\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lightdesign.shop\\\/en\\\/shop\\\/home-accessories\\\/gift-ideas\\\/foscarini-chapeaux-v-tavolo-grigio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.lightdesign.shop\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo.png\",\"width\":1027,\"height\":759,\"caption\":\"LiD Srl\"}]}<\/script>\n<meta property=\"product:brand\" content=\"Foscarini\" \/>\n<meta property=\"product:price:amount\" content=\"966\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"FN3140T200-24E00\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Palermo\" \/>\n<meta name=\"geo.position\" content=\"38.1249528;13.3539442\" \/>\n<meta name=\"geo.region\" content=\"Italy\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Foscarini CHAPEAUX V tavolo - grigio - LiD Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/","og_locale":"en_US","og_type":"article","og_title":"Foscarini CHAPEAUX V tavolo - grigio","og_description":"Chapeaux V, del marchio Foscarini, design di Rodolfo Dordoni, \u00e8 una lampada da tavolo a luce diretta e diffusa, elegante e minimale. Il cuore del progetto \u00e8 costituito da tre diffusori intercambiabili \u2013 diversi per forma, materiali e finiture \u2013 appoggiati liberamente su un corpo cilindrico in vetro borosilicato aperto alle estremit\u00e0, che ospita anche la fonte luminosa. Questa, racchiusa in un\u2019ampolla in policarbonato opalino, sembra galleggiare all\u2019interno del vetro.","og_url":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/","og_site_name":"LiD Design","article_publisher":"https:\/\/www.facebook.com\/LID-Design-757324454392843\/","article_modified_time":"2026-05-07T15:38:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/12\/FN3140T200_24E00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;&nbsp;966","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/","url":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/","name":"Foscarini CHAPEAUX V tavolo - grigio - LiD Design","isPartOf":{"@id":"https:\/\/www.lightdesign.shop\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#primaryimage"},"image":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/12\/FN3140T200_24E00.jpg","datePublished":"2024-12-12T09:24:30+00:00","dateModified":"2026-05-07T15:38:57+00:00","breadcrumb":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#primaryimage","url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/12\/FN3140T200_24E00.jpg","contentUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/12\/FN3140T200_24E00.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lightdesign.shop\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.lightdesign.shop\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Foscarini CHAPEAUX V tavolo &#8211; grigio"}]},{"@type":"WebSite","@id":"https:\/\/www.lightdesign.shop\/en\/#website","url":"https:\/\/www.lightdesign.shop\/en\/","name":"LiD - illumina il tuo mondo","description":"Light Design Shop","publisher":{"@id":"https:\/\/www.lightdesign.shop\/en\/#organization"},"alternateName":"lightdesign.shop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lightdesign.shop\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/www.lightdesign.shop\/en\/#organization","name":"LiD Srl","alternateName":"LID design","url":"https:\/\/www.lightdesign.shop\/en\/","logo":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/LID-Design-757324454392843\/","https:\/\/www.instagram.com\/lightdesign.shop\/","https:\/\/www.youtube.com\/channel\/UC-wfhs9IlrFGpIWzx24cMhA"],"legalName":"Lid Srl","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.lightdesign.shop\/termini-e-condizioni\/"},"address":{"@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"38.1249528","longitude":"13.3539442"},"telephone":["0917478460","+393756953950"],"contactPoint":{"@type":"ContactPoint","telephone":"+393756953950","email":"customerservice@liddesign.it"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@liddesign.it","vatID":"IT06602130822"},{"@type":"PostalAddress","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#local-main-place-address","streetAddress":"via xx settembre 9","addressLocality":"Palermo","postalCode":"90141","addressRegion":"PA","addressCountry":"IT"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lightdesign.shop\/en\/shop\/home-accessories\/gift-ideas\/foscarini-chapeaux-v-tavolo-grigio\/#local-main-organization-logo","url":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/06\/logo.png","contentUrl":"https:\/\/www.lightdesign.shop\/wp-content\/uploads\/2024\/06\/logo.png","width":1027,"height":759,"caption":"LiD Srl"}]},"product_brand":"Foscarini","product_price_amount":"966","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"FN3140T200-24E00","product_condition":"new","geo.placename":"Palermo","geo.position":{"lat":"38.1249528","long":"13.3539442"},"geo.region":"Italy"},"_links":{"self":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product\/1316211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/comments?post=1316211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/media\/1314857"}],"wp:attachment":[{"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/media?parent=1316211"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_brand?post=1316211"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_cat?post=1316211"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lightdesign.shop\/en\/wp-json\/wp\/v2\/product_tag?post=1316211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}